{"id":132832,"date":"2026-07-04T13:27:00","date_gmt":"2026-07-04T16:27:00","guid":{"rendered":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/hikvision-conquista-a-primeira-certificacao-eucc-do-setor-para-cameras-de-rede\/"},"modified":"2026-07-04T13:27:00","modified_gmt":"2026-07-04T16:27:00","slug":"hikvision-conquista-a-primeira-certificacao-eucc-do-setor-para-cameras-de-rede","status":"publish","type":"post","link":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/hikvision-conquista-a-primeira-certificacao-eucc-do-setor-para-cameras-de-rede\/","title":{"rendered":"Hikvision conquista a primeira certifica\u00e7\u00e3o EUCC do setor para c\u00e2meras de rede"},"content":{"rendered":"\n<div class=\"xn-content\">\n<span class=\"legendSpanClass\">HANGZHOU, China<\/span>, <span class=\"legendSpanClass\">4 de julho de 2026<\/span> \/PRNewswire\/ &#8212; A Hikvision anunciou que sua s\u00e9rie de c\u00e2meras de rede DeepinView (iDS-2CD7x) conquistou a certifica\u00e7\u00e3o EUCC (European Cybersecurity Certification Scheme based on Common Criteria &#8211; Estrutura Europeia de Certifica\u00e7\u00e3o em Ciberseguran\u00e7a baseada no Common Criteria). Esse marco torna a s\u00e9rie o primeiro produto da categoria de c\u00e2meras de CFTV do mundo a conquistar essa certifica\u00e7\u00e3o, refor\u00e7ando o compromisso da Hikvision com a seguran\u00e7a de seus produtos e a conformidade de sua governan\u00e7a digital.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder1\">\n<a href=\"https:\/\/mma.prnewswire.com\/media\/3003747\/image1.html\" target=\"_blank\" rel=\"nofollow\">  <img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/3003747\/image1.jpg\" title=\"Hikvision conquista a primeira certifica\u00e7\u00e3o EUCC do setor para c\u00e2meras de rede (PRNewsfoto\/Hikvision)\" alt=\"Hikvision conquista a primeira certifica\u00e7\u00e3o EUCC do setor para c\u00e2meras de rede (PRNewsfoto\/Hikvision)\" \/><\/a>\n <\/p>\n<\/p><\/div>\n<p>A certifica\u00e7\u00e3o foi concedida pela TrustCB B.V., organismo independente de certifica\u00e7\u00e3o autorizado pela Autoridade Holandesa para Infraestrutura Digital (RDI). A avalia\u00e7\u00e3o abrangente de seguran\u00e7a foi conduzida pela Bureau Veritas Cybersecurity Europe, laborat\u00f3rio independente de testes reconhecido internacionalmente. Realizada em conformidade com as normas ISO\/IEC 15408 (Common Criteria) e CEM:2022 R1, a s\u00e9rie certificada iDS-2CD7x atende ao n\u00edvel de garantia &#8220;Substantial&#8221; da EUCC, alinhado ao N\u00edvel de Garantia de Avalia\u00e7\u00e3o 3 (EAL3) e complementado pelo requisito ALC_FLR.2 (Corre\u00e7\u00e3o de Falhas).<\/p>\n<p><b>Atendendo ao novo cen\u00e1rio europeu de certifica\u00e7\u00e3o em ciberseguran\u00e7a<\/b><\/p>\n<p>Adotada recentemente como refer\u00eancia para a certifica\u00e7\u00e3o de ciberseguran\u00e7a de produtos na Europa, a EUCC \u00e9 baseada nos padr\u00f5es internacionalmente reconhecidos do Common Criteria (CC). A estrutura utiliza testes e auditorias independentes e rigorosos para verificar, de forma sistem\u00e1tica, os recursos de seguran\u00e7a dos produtos, seus processos de desenvolvimento e a gest\u00e3o de vulnerabilidades.<\/p>\n<p>\u00c0 medida que a Uni\u00e3o Europeia fortalece os requisitos de seguran\u00e7a para produtos digitais &#8212; com iniciativas como o Cyber Resilience Act (CRA), que estabelece exig\u00eancias de seguran\u00e7a ao longo de todo o ciclo de vida de &#8220;produtos com elementos digitais&#8221;, e a Diretiva NIS2, que amplia as obriga\u00e7\u00f5es de ciberseguran\u00e7a para setores cr\u00edticos &#8211;, a EUCC consolida-se como uma refer\u00eancia confi\u00e1vel. Ela oferece a fabricantes e usu\u00e1rios finais uma comprova\u00e7\u00e3o padronizada e confi\u00e1vel de conformidade, servindo como refer\u00eancia para setores com elevados requisitos de seguran\u00e7a, como governo, infraestrutura cr\u00edtica, energia e transporte.<\/p>\n<p><b>Uma abordagem estruturada baseada no conceito &#8220;Seguran\u00e7a desde a Concep\u00e7\u00e3o&#8221;<\/b><\/p>\n<p>No atual cen\u00e1rio digital altamente interconectado, a ciberseguran\u00e7a deixou de ser um diferencial para se tornar um elemento essencial de confian\u00e7a. A conquista da primeira certifica\u00e7\u00e3o EUCC do mundo para a categoria de c\u00e2meras reflete a abordagem estruturada da Hikvision baseada no conceito de &#8220;Seguran\u00e7a desde a Concep\u00e7\u00e3o&#8221;. Ao incorporar rigorosos princ\u00edpios de seguran\u00e7a em todas as etapas do ciclo de vida do produto &#8212; da concep\u00e7\u00e3o e pesquisa e desenvolvimento (P&amp;D) aos testes, entrega e manuten\u00e7\u00e3o cont\u00ednua &#8211;, a empresa garante que a prote\u00e7\u00e3o dos dispositivos seja tratada de forma proativa desde a sua origem.<\/p>\n<p>A certifica\u00e7\u00e3o valida, especificamente, os robustos controles de seguran\u00e7a da s\u00e9rie iDS-2CD7x em \u00e1reas essenciais, como autentica\u00e7\u00e3o de identidade, controle de acesso, comunica\u00e7\u00f5es seguras, auditoria de seguran\u00e7a e gest\u00e3o de vulnerabilidades. Ao estabelecer esse novo marco para o setor, a empresa cria uma nova refer\u00eancia para conformidade em ciberseguran\u00e7a e refor\u00e7a ainda mais a confian\u00e7a dos clientes globais nos produtos e solu\u00e7\u00f5es da Hikvision.<\/p>\n<p>Para saber mais sobre as iniciativas de ciberseguran\u00e7a da Hikvision, acesse este <a href=\"https:\/\/www.hikvision.com\/en\/support\/cybersecurity\/\" target=\"_blank\" rel=\"nofollow\">link<\/a>.<\/p>\n<p>Foto &#8211; <a href=\"https:\/\/mma.prnewswire.com\/media\/3003747\/image1.jpg\" target=\"_blank\" rel=\"nofollow\">https:\/\/mma.prnewswire.com\/media\/3003747\/image1.jpg<\/a><\/p>\n<p id=\"PURL\"><img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=PT97701&amp;sd=2026-07-04\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/hikvision-conquista-a-primeira-certificacao-eucc-do-setor-para-cameras-de-rede-302817928.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/hikvision-conquista-a-primeira-certificacao-eucc-do-setor-para-cameras-de-rede-302817928.html<\/a><\/p>\n<p>FONTE Hikvision<\/p>\n<\/div>\n<p>  <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=PT97701&amp;Transmission_Id=202607041213PR_NEWS_LATAM____PT97701&amp;DateId=20260704\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n<p><strong>T\u00f3picos Relacionados:<\/strong> Acordos de Licenciamento\/Marketing, Seguran\u00e7a de Alta Tecnologia, Telecomunica\u00e7\u00f5es, Equipamentos de Telecomunica\u00e7\u00f5es para Operadoras\/Servi\u00e7os, Eletr\u00f4nicos de Consumo, Computador\/Eletr\u00f4nica<\/p>\n<p>A <b>OESP<\/b> n\u00e3o \u00e9(s\u00e3o) respons\u00e1vel(is) por erros, incorre\u00e7\u00f5es, atrasos ou quaisquer decis\u00f5es tomadas por seus clientes com base nos Conte\u00fados ora disponibilizados, bem como tais Conte\u00fados n\u00e3o representam a opini\u00e3o da <b>OESP<\/b> e s\u00e3o de inteira responsabilidade da <b>PR Newswire Ltda<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"HANGZHOU, China, 4 de julho de 2026 \/PRNewswire\/ &#8212; A Hikvision anunciou que sua s\u00e9rie de c\u00e2meras de rede DeepinView (iDS-2CD7x) conquistou a certifica\u00e7\u00e3o EUCC (European Cybersecurity","protected":false},"author":1,"featured_media":132833,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[11266],"class_list":["post-132832","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prnewswire","tag-a-hikvision-anunciou-que-sua-serie-de-cameras-de-rede-deepinview-ids-2cd7x-conquistou-a-certificacao-eucc-european-cybersecurity-certification-scheme-based-on-common-criteria"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/132832","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/comments?post=132832"}],"version-history":[{"count":0,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/132832\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media\/132833"}],"wp:attachment":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media?parent=132832"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/categories?post=132832"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/tags?post=132832"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}