{"id":129307,"date":"2026-05-13T11:50:00","date_gmt":"2026-05-13T14:50:00","guid":{"rendered":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/agencia-memoria-da-eletricidade\/exposicao-destaca-pioneirismo-do-rio-com-bondes-eletricos-e-debate-mobilidade-urbana\/"},"modified":"2026-05-13T11:50:00","modified_gmt":"2026-05-13T14:50:00","slug":"exposicao-destaca-pioneirismo-do-rio-com-bondes-eletricos-e-debate-mobilidade-urbana","status":"publish","type":"post","link":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/agencia-memoria-da-eletricidade\/exposicao-destaca-pioneirismo-do-rio-com-bondes-eletricos-e-debate-mobilidade-urbana\/","title":{"rendered":"Exposi\u00e7\u00e3o destaca pioneirismo do Rio com bondes el\u00e9tricos e debate mobilidade urbana"},"content":{"rendered":"<p><i>Mostra virtual da Mem\u00f3ria da Eletricidade, em parceria com a Light, relembra expans\u00e3o, queda e retomada do transporte sustent\u00e1vel na cidade<\/i><\/p>\n<p>Muito antes da discuss\u00e3o sobre carros el\u00e9tricos e mobilidade sustent\u00e1vel ganhar for\u00e7a, o Rio de Janeiro j\u00e1 tinha bondes movidos a eletricidade como o principal meio de transporte da cidade. No in\u00edcio do s\u00e9culo XX, os ve\u00edculos sobre trilhos transformaram o deslocamento da popula\u00e7\u00e3o e se tornaram um dos principais s\u00edmbolos da moderniza\u00e7\u00e3o da ent\u00e3o capital federal.<\/p>\n<p>Mais de cem anos depois, em um contexto de busca por matrizes energ\u00e9ticas mais limpas, a trajet\u00f3ria dos bondes cariocas ajuda a levantar um questionamento: como o Rio se tornou pioneiro no transporte el\u00e9trico e, posteriormente, abandonou esse modelo?A reflex\u00e3o \u00e9 um dos pontos levantados pela exposi\u00e7\u00e3o virtual \u201cA energia que iluminou o cotidiano: imagens e mem\u00f3rias do Rio de Janeiro\u201d, disponibilizada pela Mem\u00f3ria da Eletricidade na plataforma Google Arts &amp; Culture desde fevereiro.Dividida em sete blocos, com 33 imagens ao todo, a mostra, organizada em parceria com a Light, tra\u00e7a uma linha do tempo de 1880 a 1980, destacando como a reestrutura\u00e7\u00e3o e, consequentemente, a chegada da luz el\u00e9trica contribuiu para a transforma\u00e7\u00e3o do espa\u00e7o urbano, da mobilidade, da ilumina\u00e7\u00e3o p\u00fablica e dom\u00e9stica e dos h\u00e1bitos culturais dos cariocas.<\/p>\n<p><b>O Rio el\u00e9trico do in\u00edcio do s\u00e9culo XX<\/b><\/p>\n<p>A chegada da Light ao Rio, em 1904, acelerou o processo de eletrifica\u00e7\u00e3o da capital federal. Tr\u00eas anos depois, a energia el\u00e9trica passou a abastecer definitivamente a cidade tr\u00eas anos depois, em 1907, impulsionando mudan\u00e7as na ilumina\u00e7\u00e3o urbana, nos h\u00e1bitos da popula\u00e7\u00e3o e na mobilidade, com a expans\u00e3o dos bondes el\u00e9tricos.<\/p>\n<figure>\n  <img decoding=\"async\" src=\"https:\/\/www.estadaoconteudo.com.br\/RSS\/images\/AME20260513115009562113-exposiodestacapi-3.jpg\" alt=\"Circula\u00e7\u00e3o de bonde el\u00e9trico que ligava Copacabana a Ipanema. Foto: Acervo Light\"><figcaption>Circula\u00e7\u00e3o de bonde el\u00e9trico que ligava Copacabana a Ipanema. Foto: Acervo Light<\/figcaption><\/figure>\n<p>O historiador Marcus Dezemone, professor de Hist\u00f3ria do Brasil Rep\u00fablica na UFF e na UERJ, explica que o bonde \u00e9 um dos grandes s\u00edmbolos dos avan\u00e7os proporcionados pela eletrifica\u00e7\u00e3o: \u201cA energia el\u00e9trica nesse contexto representa essa melhoria nas condi\u00e7\u00f5es de vida das pessoas. Por isso, a chegada dos bondes el\u00e9tricos, com a retirada dos bondes movidos a tra\u00e7\u00e3o animal e vapor, tem um tato forte no imagin\u00e1rio carioca, tornando-se um dos principais transportes de massa na cidade\u201d. A primeira linha de bonde el\u00e9trico foi inaugurada em 1892, 12 anos antes da chegada da Light, que fazia uma pequena rota pelo bairro Largo do Machado, na Zona Sul. Em 1920, os bondes j\u00e1 eram utilizados por 84% dos cariocas, segundo dados da Prefeitura do Rio.<\/p>\n<p><b>A substitui\u00e7\u00e3o dos bondes pelo modelo rodovi\u00e1rio<\/b><\/p>\n<p>No entanto, durante as d\u00e9cadas de 1950 e 1960, iniciou-se um processo de retirada de circula\u00e7\u00e3o e desmonte dos bondes el\u00e9tricos, que ganhou mais for\u00e7a durante o governo de Juscelino Kubitschek (1957-1961). A prioridade passou a ser o transporte rodovi\u00e1rio, alinhada ao crescimento da ind\u00fastria automobil\u00edstica e ao incentivo ao uso do autom\u00f3vel.<\/p>\n<p>\u2013 Naquele momento, o petr\u00f3leo era muito barato, n\u00e3o havia a preocupa\u00e7\u00e3o ambiental dos dias de hoje, ent\u00e3o parecia ser o caminho ideal, at\u00e9 pelo efeito gerador dentro da economia, de que cada pessoa, cada fam\u00edlia, precisa ter um autom\u00f3vel. A partir disso, priorizaram-se os transportes de massa com motor a combust\u00e3o no Rio, que, na verdade, s\u00e3o de menor escala, j\u00e1 que um \u00f4nibus, por maior que seja, n\u00e3o consegue transportar a mesma quantidade de pessoas que os bondes \u2013 contextualiza Dezemone.<\/p>\n<p><b>O retorno dos trilhos com o VLT<\/b><\/p>\n<p>D\u00e9cadas depois, come\u00e7ariam a ganhar for\u00e7as os bondes el\u00e9tricos \u201cmodernos\u201d, chamados de Ve\u00edculo Leve sobre Trilhos (VLT). A ado\u00e7\u00e3o ao modal acelerou a partir dos anos 2000, e a cidade do Rio recebeu em 2016, uma das principais interven\u00e7\u00f5es de mobilidade urbana para os Jogos Ol\u00edmpicos de 2016. Atualmente, o VLT Carioca opera em toda a Regi\u00e3o Central da cidade, com quatro linhas.<\/p>\n<figure>\n  <img decoding=\"async\" src=\"https:\/\/www.estadaoconteudo.com.br\/RSS\/images\/AME20260513115009562113-exposiodestacapi-2.jpg\" alt=\"Circula\u00e7\u00e3o do VLT Carioca. Foto: Divulga\u00e7\u00e3o\"><figcaption>Circula\u00e7\u00e3o do VLT Carioca. Foto: Divulga\u00e7\u00e3o<\/figcaption><\/figure>\n<p>Ainda assim, o transporte nunca conseguiu atingir a expectativa de m\u00e9dia de passageiros. A proje\u00e7\u00e3o inicial era de 300 mil por dia em opera\u00e7\u00e3o plena, mas a quantidade real ficou em torno de 80 mil em dias \u00fateis. Para Marcus Dezemone, a retomada dos transportes sobre trilhos acompanha uma tend\u00eancia internacional, mas ainda enfrenta desafios de integra\u00e7\u00e3o e alcance dentro da cidade.\u2013 Acredito que se os VLTs fossem implementados em outros corredores da cidade, como por exemplo na Zona Sul, retirando coletivos da rua, eles teriam maior uso. Tamb\u00e9m o eixo ali da Avenida das Am\u00e9ricas, que tem o \u00f4nibus e o BRT. \u00c9 uma tend\u00eancia, vemos isso no mundo todo, ainda mais pela busca de uma matriz energ\u00e9tica mais limpa \u2013 conclui o historiador.<\/p>\n<p><b>Como visitar a exposi\u00e7\u00e3o<\/b><\/p>\n<p>\u201c <a href=\"https:\/\/artsandculture.google.com\/story\/ygXhANeSNROlRg\" target=\"_blank\"><u>A energia que iluminou o cotidiano: imagens e mem\u00f3rias do Rio de Janeiro<\/u><\/a> \u201d, a terceira da Mem\u00f3ria da Eletricidade na plataforma, pode ser visitada gratuitamente. As outras contam a hist\u00f3ria da <a href=\"https:\/\/artsandculture.google.com\/story\/TQWBvMUUpFJMag\" target=\"_blank\"><u>Usina Hidrel\u00e9trica Alberto Torres (Piabanha)<\/u><\/a>, fundamental para a eletrifica\u00e7\u00e3o do estado do Rio, e da <a href=\"https:\/\/artsandculture.google.com\/story\/iwXBLUOIVBrbXQ\" target=\"_blank\"><u>Exposi\u00e7\u00e3o Nacional de 1908<\/u><\/a>, grande solenidade realizada na cidade.<\/p>\n<figure>\n  <img decoding=\"async\" src=\"https:\/\/www.estadaoconteudo.com.br\/RSS\/images\/AME20260513115009562113-exposiodestacapi-1.jpg\" alt=\"Obras de instala\u00e7\u00e3o de trilhos na avenida Marechal Floriano, no Centro do Rio. Foto: Acervo Light\"><figcaption>Obras de instala\u00e7\u00e3o de trilhos na avenida Marechal Floriano, no Centro do Rio. Foto: Acervo Light<\/figcaption><\/figure>\n<p>A Mem\u00f3ria da Eletricidade \u00e9 uma institui\u00e7\u00e3o sem fins lucrativos dedicada \u00e0 preserva\u00e7\u00e3o e difus\u00e3o da hist\u00f3ria do setor el\u00e9trico brasileiro. Desde 1986, realiza projetos de pesquisa hist\u00f3rica, conserva\u00e7\u00e3o de acervos, produ\u00e7\u00e3o de publica\u00e7\u00f5es e coleta de relatos de hist\u00f3ria oral, promovendo o conhecimento sobre a trajet\u00f3ria e os desafios da energia no Brasil. Seu acervo re\u00fane milhares de documentos, fotografias, v\u00eddeos e registros sonoros que contam a evolu\u00e7\u00e3o do setor el\u00e9trico e podem ser acessados no<\/p>\n<p><a href=\"https:\/\/memoriadaeletricidade.com.br\/acervo\" target=\"_blank\"><u>site<\/u><\/a>.<\/p>\n<p>A <b>OESP<\/b> n\u00e3o \u00e9(s\u00e3o) respons\u00e1vel(is) por erros, incorre\u00e7\u00f5es, atrasos ou quaisquer decis\u00f5es tomadas por seus clientes com base nos Conte\u00fados ora disponibilizados, bem como tais Conte\u00fados n\u00e3o representam a opini\u00e3o da <b>OESP<\/b> e s\u00e3o de inteira responsabilidade da <b>Ag\u00eancia Mem\u00f3ria da Eletricidade<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"Mostra virtual da Mem\u00f3ria da Eletricidade, em parceria com a Light, relembra expans\u00e3o, queda e retomada do transporte sustent\u00e1vel na cidade Muito antes da discuss\u00e3o sobre carros el\u00e9tricos e","protected":false},"author":1,"featured_media":129308,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[1680],"tags":[],"class_list":["post-129307","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-agencia-memoria-da-eletricidade"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/129307","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/comments?post=129307"}],"version-history":[{"count":0,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/129307\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media\/129308"}],"wp:attachment":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media?parent=129307"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/categories?post=129307"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/tags?post=129307"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}