{"id":129291,"date":"2026-05-13T09:57:00","date_gmt":"2026-05-13T12:57:00","guid":{"rendered":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/atlas-ai-labs-lancara-o-primeiro-token-lastreado-em-ativos-sem-permissao-a-partir-de-dubai\/"},"modified":"2026-05-13T09:57:00","modified_gmt":"2026-05-13T12:57:00","slug":"atlas-ai-labs-lancara-o-primeiro-token-lastreado-em-ativos-sem-permissao-a-partir-de-dubai","status":"publish","type":"post","link":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/atlas-ai-labs-lancara-o-primeiro-token-lastreado-em-ativos-sem-permissao-a-partir-de-dubai\/","title":{"rendered":"Atlas AI Labs lan\u00e7ar\u00e1 o primeiro token lastreado em ativos sem permiss\u00e3o a partir de Dubai"},"content":{"rendered":"\n<div class=\"xn-content\">\n<ul type=\"disc\">\n<li><i>Atlas AI Labs recebe aprova\u00e7\u00e3o preliminar da VARA para operar &#8212; a primeira aprova\u00e7\u00e3o concedida para o lan\u00e7amento de um token lastreado em ativos, emitido e negociado em um ambiente totalmente sem permiss\u00e3o<\/i><\/li>\n<li><i>O token USAF+ da Atlas estabelece uma nova categoria de tokens lastreados em ativos: ativos reais, arquitetura aberta e acesso 24 horas por dia, 7 dias por semana<\/i><\/li>\n<li><i>Apoiado pelo Atlas America Fund ETF (NASDAQ: USAF), cujo Comit\u00ea de Investimentos \u00e9 presidido pelo Dr. Nouriel Roubini<\/i><\/li>\n<\/ul>\n<p><span class=\"legendSpanClass\">DUBAI, Emirados \u00c1rabes Unidos<\/span>, <span class=\"legendSpanClass\">13 de maio de 2026<\/span> \/PRNewswire\/ &#8212; A Atlas AI Labs FZE (<b>Atlas<\/b>), subsidi\u00e1ria constitu\u00edda em Dubai da Atlas Capital Team Inc., uma empresa de tecnologia financeira sediada nos Estados Unidos, est\u00e1 prestes a lan\u00e7ar o primeiro ativo virtual lastreado em ativos dispon\u00edveis em um ambiente totalmente sem permiss\u00e3o, representando um divisor de \u00e1guas tanto para as finan\u00e7as tradicionais quanto para as digitais. Isso ocorre ap\u00f3s a aprova\u00e7\u00e3o preliminar (IPA) concedida pela Autoridade Reguladora de Ativos Virtuais de Dubai (<b>VARA<\/b>) para a presta\u00e7\u00e3o de servi\u00e7os de emiss\u00e3o de tokens nos termos do seu Regulamento de Ativos Virtuais Indexados a Ativos (<b>ARVA<\/b>).<\/p>\n<p>O token, que ser\u00e1 emitido sob o nome USAF+, \u00e9 uma representa\u00e7\u00e3o digital totalmente garantida pelo Atlas America Fund (NASDAQ: USAF), um ETF registrado na SEC cujos ativos s\u00e3o mantidos em cust\u00f3dia pelo Bank of New York. O valor patrimonial l\u00edquido (NAV) do token est\u00e1 diretamente indexado ao NAV subjacente do ETF da USAF. A transpar\u00eancia e a presta\u00e7\u00e3o de contas relativas ao lastro de reservas do USAF+ seguem o mesmo cronograma e formato de divulga\u00e7\u00e3o do ETF tradicional e ser\u00e3o certificadas por um auditor externo. A carteira \u00e9 composta por t\u00edtulos do Tesouro dos EUA de curto prazo, TIPS e t\u00edtulos municipais, ouro, im\u00f3veis resilientes \u00e0s mudan\u00e7as clim\u00e1ticas e fundos de investimento imobili\u00e1rio (REITs), a\u00e7\u00f5es dos setores de defesa e seguran\u00e7a cibern\u00e9tica, al\u00e9m de commodities agr\u00edcolas e energ\u00e9ticas.<\/p>\n<p>A aloca\u00e7\u00e3o de ativos \u00e9 gerenciada proativamente sob uma estrutura adapt\u00e1vel, que se ajusta dinamicamente em tempo real \u00e0s mudan\u00e7as no ambiente de mercado. Para isso, a pesquisa cont\u00ednua e o apoio operacional da Atlas AI Labs, sob a supervis\u00e3o do Comit\u00ea de Investimentos da Atlas Capital Team Inc., s\u00e3o essenciais. Esta arquitetura foi concebida para oferecer estabilidade, verificabilidade e liquidez de n\u00edvel institucional em todos os cen\u00e1rios macroecon\u00f4micos.<\/p>\n<p>O grande diferencial do USAF+ \u00e9 sua arquitetura aberta. Por ser um token lastreado em ativos reais e feito para ser emitido em um ambiente sem restri\u00e7\u00f5es, ele estar\u00e1 acess\u00edvel, poder\u00e1 ser negociado e liquidado 24 horas por dia, 7 dias por semana, sem a interven\u00e7\u00e3o de intermedi\u00e1rios. Isso democratiza o acesso a ativos do mundo real tokenizados para um p\u00fablico global, ao mesmo tempo em que preserva a supervis\u00e3o regulat\u00f3ria exigida pelos mercados institucionais. O USAF+ ser\u00e1 o primeiro ativo digital garantido simultaneamente por um ETF registrado na SEC e listado na NASDAQ e aprovado pela VARA para emiss\u00e3o sem permiss\u00e3o.<\/p>\n<p><b>Reza Bundy, CEO e presidente da Atlas Capital Team Inc., afirmou:<\/b> &#8220;Isso \u00e9 um divisor de \u00e1guas para as finan\u00e7as digitais. Pela primeira vez, qualquer pessoa, em qualquer lugar, poder\u00e1 deter e negociar um token regulamentado e lastreado em ativos reais em um ambiente sem permiss\u00e3o. Essa arquitetura existe gra\u00e7as \u00e0 estrutura regulat\u00f3ria desenvolvida por Dubai, especialmente para ela. &#8220;O Regulamento ARVA da VARA \u00e9 o primeiro regime do mundo a autorizar a emiss\u00e3o sem permiss\u00e3o de ativos virtuais indexados a ativos reais, e os Emirados \u00c1rabes Unidos combinaram essa clareza regulat\u00f3ria com uma abertura operacional que nenhum outro centro financeiro consegue igualar.&#8221;<\/p>\n<p><b>Um porta-voz da VARA acrescenta:<\/b> &#8220;Essa aprova\u00e7\u00e3o demonstra o compromisso da VARA em possibilitar uma nova categoria de finan\u00e7as digitais regulamentadas e lastreadas em ativos, al\u00e9m de consolidar ainda mais a posi\u00e7\u00e3o dos Emirados \u00c1rabes Unidos como um centro global para a inova\u00e7\u00e3o em ativos digitais regulamentados.&#8221; &#8220;Esse compromisso \u00e9 um avan\u00e7o consider\u00e1vel tanto para os mercados de capitais quanto para o ecossistema de ativos virtuais.&#8221;<\/p>\n<p>Essa novidade tamb\u00e9m representa a primeira incurs\u00e3o no mundo dos ativos digitais do Dr. Nouriel Roubini, ex-consultor s\u00eanior do Tesouro dos Estados Unidos e ex-economista s\u00eanior da Casa Branca. O USAF+ \u00e9 garantido pelo ETF Atlas America Fund, no qual o Dr. Roubini preside o Comit\u00ea de Investimentos, trazendo a credibilidade de um macroeconomista de renome mundial para o setor de ativos tokenizados.<\/p>\n<p><b>O Dr. Nouriel Roubini, economista-chefe e cofundador da Atlas Capital Team Inc., comenta:<\/b> &#8220;\u00c9 na interse\u00e7\u00e3o entre o rigor macroecon\u00f4mico e a inova\u00e7\u00e3o digital que ser\u00e1 constru\u00edda a pr\u00f3xima gera\u00e7\u00e3o de infraestrutura financeira, e Dubai se posicionou como uma das poucas jurisdi\u00e7\u00f5es onde esse trabalho pode ser colocado em pr\u00e1tica.&#8221; O Atlas America Fund e sua tokeniza\u00e7\u00e3o s\u00e3o a comprova\u00e7\u00e3o dessa tese. Em um momento de elevada volatilidade macroecon\u00f4mica, os investidores precisam de garantias capazes de manter seu valor em diferentes contextos, gerar rendimento a partir de ativos reais e agir com a rapidez exigida pelos mercados digitais. A Atlas busca oferecer esses tr\u00eas aspectos, dentro de uma estrutura regulat\u00f3ria que os Emirados \u00c1rabes Unidos criaram especificamente para essa categoria.<\/p>\n<p><b>Notas aos editores<br \/><\/b><b>Sobre a Atlas AI Labs FZE<br \/><\/b>A Atlas AI Labs FZE, sediada no Dubai World Trade Centre, \u00e9 uma subsidi\u00e1ria integral da Atlas Capital Team Inc., uma empresa de tecnologia financeira com sede nos Estados Unidos, cofundada pelo Sr. Reza Bundy e pelo Dr. Nouriel Roubini.<\/p>\n<p><b>Para consultas de m\u00eddia, entre em contato com: <\/b><a href=\"mailto:media@atlascap.io\" target=\"_blank\" rel=\"nofollow\">media@atlascap.io<\/a><\/p>\n<\/p>\n<\/p>\n<p id=\"PURL\"><img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=PT57149&amp;sd=2026-05-12\" \/> View original content:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/atlas-ai-labs-lancara-o-primeiro-token-lastreado-em-ativos-sem-permissao-a-partir-de-dubai-302770933.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/atlas-ai-labs-lancara-o-primeiro-token-lastreado-em-ativos-sem-permissao-a-partir-de-dubai-302770933.html<\/a><\/p>\n<p>FONTE Atlas Capital Team Inc.<\/p>\n<\/div>\n<p>  <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=PT57149&amp;Transmission_Id=202605120900PR_NEWS_LATAM____PT57149&amp;DateId=20260513\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n<p><strong>T\u00f3picos Relacionados:<\/strong> Novos Produtos\/Servi\u00e7os, Tecnologia Financeira, Criptomoeda, Computador\/Eletr\u00f4nica, Servi\u00e7os Banc\u00e1rios\/Financeiros, Intelig\u00eancia Artificial<\/p>\n<p>A <b>OESP<\/b> n\u00e3o \u00e9(s\u00e3o) respons\u00e1vel(is) por erros, incorre\u00e7\u00f5es, atrasos ou quaisquer decis\u00f5es tomadas por seus clientes com base nos Conte\u00fados ora disponibilizados, bem como tais Conte\u00fados n\u00e3o representam a opini\u00e3o da <b>OESP<\/b> e s\u00e3o de inteira responsabilidade da <b>PR Newswire Ltda<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"Atlas AI Labs recebe aprova\u00e7\u00e3o preliminar da VARA para operar &#8212; a primeira aprova\u00e7\u00e3o concedida para o lan\u00e7amento de um token lastreado em ativos, emitido e negociado em um ambiente","protected":false},"author":1,"featured_media":129292,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[9642,9645,9643,9644],"class_list":["post-129291","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prnewswire","tag-a-atlas-ai-labs-fze-atlas","tag-esta-prestes-a-la","tag-subsidiaria-constituida-em-dubai-da-atlas-capital-team-inc","tag-uma-empresa-de-tecnologia-financeira-sediada-nos-estados-unidos"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/129291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/comments?post=129291"}],"version-history":[{"count":0,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/129291\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media\/129292"}],"wp:attachment":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media?parent=129291"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/categories?post=129291"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/tags?post=129291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}