{"id":123344,"date":"2026-01-28T08:57:00","date_gmt":"2026-01-28T11:57:00","guid":{"rendered":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/novo-estudo-identifica-inflamacao-oculta-no-couro-cabeludo-que-pode-explicar-por-que-os-tratamentos-para-a-calvicie-androgenetica-param-de-funcionar\/"},"modified":"2026-01-28T08:57:00","modified_gmt":"2026-01-28T11:57:00","slug":"novo-estudo-identifica-inflamacao-oculta-no-couro-cabeludo-que-pode-explicar-por-que-os-tratamentos-para-a-calvicie-androgenetica-param-de-funcionar","status":"publish","type":"post","link":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/novo-estudo-identifica-inflamacao-oculta-no-couro-cabeludo-que-pode-explicar-por-que-os-tratamentos-para-a-calvicie-androgenetica-param-de-funcionar\/","title":{"rendered":"Novo estudo identifica inflama\u00e7\u00e3o oculta no couro cabeludo que pode explicar por que os tratamentos para a calv\u00edcie androgen\u00e9tica param de funcionar"},"content":{"rendered":"\n<div class=\"xn-content\">\nArtigo de acesso aberto descreve PIILIF, um padr\u00e3o inflamat\u00f3rio e fibr\u00f3tico precoce centrado nos fol\u00edculos, encontrado mesmo em couros cabeludos com apar\u00eancia normal.<\/p>\n<p><span class=\"legendSpanClass\">MANHATTAN BEACH, Calif\u00f3rnia<\/span>, <span class=\"legendSpanClass\">28 de janeiro de 2026<\/span> \/PRNewswire\/ &#8212; Pesquisadores da Cl\u00ednica Dr. U Hair and Skin, na regi\u00e3o de Los Angeles, relatam que um padr\u00e3o inflamat\u00f3rio e fibr\u00f3tico precoce na alopecia androgen\u00e9tica (AGA), calv\u00edcie masculina e queda de cabelo feminina, pode ajudar a explicar por que algumas pessoas deixam de responder aos tratamentos padr\u00e3o &#8220;apenas para AGA&#8221; e por que os resultados podem ser imprevis\u00edveis em casos avan\u00e7ados ou complexos. Os resultados aparecem no peri\u00f3dico <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=pt&amp;o=4604135-1&amp;h=693619955&amp;u=https%3A%2F%2Fedge.prnewswire.com%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D4604135-1%26h%3D2369149604%26u%3Dhttps%253A%252F%252Fwww.dovepress.com%252Fperifollicular-inflammation-and-fibrosis-in-androgenetic-alopecia-impl-peer-reviewed-fulltext-article-CCID%26a%3DClinical%252C%2BCosmetic%2Band%2BInvestigational%2BDermatology&amp;a=Clinical%2C+Cosmetic+and+Investigational+Dermatology\" target=\"_blank\" rel=\"nofollow\">Clinical, Cosmetic and Investigational Dermatology<\/a>.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder2768\">\n<p title=\"V\u00eddeo: O Dr. Sanusi Umar discute a PIILIF, um padr\u00e3o inflamat\u00f3rio e fibr\u00f3tico precoce centrado nos fol\u00edculos, e suas implica\u00e7\u00f5es cl\u00ednicas usando um caso representativo de alopecia androgen\u00e9tica complexa.\">\n<\/div>\n<p>O artigo descreve o PIILIF, um padr\u00e3o inflamat\u00f3rio e fibr\u00f3tico precoce centrado em torno da parte superior do fol\u00edculo piloso. O PIILIF pode coexistir com a AGA e pode estar presente mesmo quando o couro cabeludo tem uma apar\u00eancia normal. <\/p>\n<p>&#8220;Muitas pessoas que sofrem de queda de cabelo fazem tudo certo, incluindo o uso de minoxidil, finasterida e at\u00e9 mesmo transplante capilar, mas ainda assim obt\u00eam resultados decepcionantes&#8221;, disse Sanusi Umar, m\u00e9dico dermatologista certificado e principal autor do estudo. &#8220;Em um subconjunto significativo de pacientes com AGA, um fator inflamat\u00f3rio e um fator fibr\u00f3tico precoce podem estar atuando em paralelo. Quando essa biologia \u00e9 ignorada, os resultados ficam abaixo do esperado, como foi previsto.&#8221;<\/p>\n<p>Desenvolvimento do estudo e principais resultados Os pesquisadores analisaram retrospectivamente 129 pacientes com AGA de uma coorte de um centro de refer\u00eancia. Usando imagens de alta amplia\u00e7\u00e3o para orientar bi\u00f3psias de couro cabeludo com afinamento e apar\u00eancia normal, eles relacionaram os achados microsc\u00f3picos \u00e0s caracter\u00edsticas cl\u00ednicas e aos resultados.<\/p>\n<p>Os destaques incluem: * O PIILIF foi identificado em couros cabeludos com apar\u00eancia normal em 81% dos pacientes, especialmente entre pacientes com mais de 44 anos, com perda de cabelo avan\u00e7ada ou calv\u00edcie, ou resposta insatisfat\u00f3ria anterior. * Apesar de frequentemente ser rotulada como &#8220;dermatite seborreica&#8221; ou &#8220;caspa&#8221;, a verdadeira dermatite seborreica foi confirmada na bi\u00f3psia em apenas 0,8% da coorte; PIILIF estava presente em 81%. * Entre os pacientes com AGA-PIILIF avali\u00e1veis tratados com um plano que abordava os fatores hormonais e a inflama\u00e7\u00e3o imunol\u00f3gica centrada nos fol\u00edculos, 67% apresentaram melhora e 2% tiveram resultados abaixo do ideal. * Os resultados apoiam um espectro AGA-PIILIF e sugerem uma estrat\u00e9gia de dupla via, controle hormonal e imunol\u00f3gico inflamat\u00f3rio\/fibr\u00f3tico quando indicado, no tratamento da queda de cabelo resistente ao tratamento e calv\u00edcie padr\u00e3o.<\/p>\n<p>O artigo tamb\u00e9m prop\u00f5e que a alopecia fibrosante de distribui\u00e7\u00e3o padronizada (fibrosing alopecia of patterned distribution, FAPD) se alinha com um est\u00e1gio mais avan\u00e7ado da AGA-PIILIF e recomenda o estadiamento da AGA-PIILIF por fibrose perifolicular para apoiar o reconhecimento e a interven\u00e7\u00e3o precoces.<\/p>\n<p>O que isso significa para as pessoas que n\u00e3o est\u00e3o respondendo \u00e0 terapia A maioria dos planos se concentra no controle da diidrotestosterona (DHT) e no suporte ao ciclo folicular com finasterida e minoxidil. Mas quando a inflama\u00e7\u00e3o do tipo imunol\u00f3gico e a fibrose precoce est\u00e3o ativas ao redor dos fol\u00edculos, &#8220;mais do mesmo&#8221; pode n\u00e3o ser suficiente. Isso n\u00e3o significa que todos precisem de uma bi\u00f3psia. Para os pacientes que n\u00e3o respondem ao tratamento, o estudo defende um melhor controle biol\u00f3gico, um melhor direcionamento e um melhor momento de interven\u00e7\u00e3o, com confirma\u00e7\u00e3o diagn\u00f3stica mais precoce em casos pouco claros ou de alto risco.<\/p>\n<p>Cuidados a longo prazo s\u00e3o importantes Quando o PIILIF est\u00e1 presente, o objetivo n\u00e3o \u00e9 apenas estimular o crescimento do cabelo, mas tamb\u00e9m estabilizar o ambiente do couro cabeludo. Os resultados apoiam estrat\u00e9gias anti-inflamat\u00f3rias de longo prazo, com pouca utiliza\u00e7\u00e3o de ester\u00f3ides, semelhantes em princ\u00edpio \u00e0s abordagens utilizadas nas alopecias cicatriciais, quando clinicamente apropriado.<\/p>\n<p>Por que isso \u00e9 importante para o planejamento do transplante capilar Em casos avan\u00e7ados, com doadores limitados, reparos ou desempenho insatisfat\u00f3rio p\u00f3s-procedimento, a biologia do couro cabeludo pode afetar a previsibilidade e a durabilidade. Quando h\u00e1 suspeita de biologia de padr\u00e3o inflamat\u00f3rio, os resultados apoiam a otimiza\u00e7\u00e3o do couro cabeludo e o planejamento baseado em bi\u00f3psia, em vez de recorrer automaticamente a enxertos adicionais.<\/p>\n<p><b>Traduzindo os achados para a pr\u00e1tica cl\u00ednica <\/b> Os autores incentivam os m\u00e9dicos a adotarem vias estruturadas de triagem e tratamento para reconhecer mais cedo a AGA de padr\u00e3o inflamat\u00f3rio e integrar o tratamento de longo prazo de via dupla, quando indicado. O Dr. Umar apresenta um exemplo, o <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=pt&amp;o=4604135-1&amp;h=1684235162&amp;u=https%3A%2F%2Fedge.prnewswire.com%2Fc%2Flink%2F%3Ft%3D0%26l%3Den%26o%3D4604135-1%26h%3D1624284955%26u%3Dhttps%253A%252F%252Fdru.com%252Fpiilif-track-intake%252F%26a%3DInflammatory%2BAGA%2BScreen%2B(PIILIF%2BTrack)&amp;a=Inflammatory+AGA+Screen+(PIILIF+Track)\" target=\"_blank\" rel=\"nofollow\">Inflammatory AGA Screen (PIILIF Track)<\/a> , como um modelo que outros podem adotar e refinar.<\/p>\n<p>Nota m\u00e9dica: este comunicado \u00e9 para fins informativos e n\u00e3o fornece aconselhamento m\u00e9dico. Os resultados individuais podem variar.<\/p>\n<p>Contato para a imprensa: Alice Lee, coordenadora de rela\u00e7\u00f5es p\u00fablicas, Cl\u00ednica Dr. U Hair and Skin; Telefone: +1-310-318-1500, e-mail: <a href=\"mailto:AliceL@dru.com\" target=\"_blank\" rel=\"nofollow\">AliceL@dru.com<\/a> <\/p>\n<p>Sanusi Umar, MD, \u00e9 dermatologista certificado, fundador da Cl\u00ednica Dr. U Hair and Skin em Manhattan Beach e instrutor cl\u00ednico na UCLA e Harbor-UCLA, especializado em casos complexos de queda de cabelo, calv\u00edcie, alopecia cicatricial, AGA avan\u00e7ada, quel\u00f3ides e reparos.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder2375\">\n<a href=\"https:\/\/mma.prnewswire.com\/media\/2870362\/Dr__U_Hair_and_Skin_Clinic__piilif_aga_norwood_7_strip_scar_hair_transplant_before_after.html\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/2870362\/Dr__U_Hair_and_Skin_Clinic__piilif_aga_norwood_7_strip_scar_hair_transplant_before_after.jpg\" title=\"A patient with Norwood 7 pattern baldness and a prior strip-surgery treatment scar before treatment (left) and eight months after hair transplantation performed alongside PIILIF-directed management (right). Individual results vary. (PRNewsfoto\/Dr. U Hair and Skin Clinic)\" alt=\"A patient with Norwood 7 pattern baldness and a prior strip-surgery treatment scar before treatment (left) and eight months after hair transplantation performed alongside PIILIF-directed management (right). Individual results vary. (PRNewsfoto\/Dr. U Hair and Skin Clinic)\" \/><\/a><\/p>\n<\/div>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder9308\">\n<a href=\"https:\/\/mma.prnewswire.com\/media\/2170144\/Dr_U_Hair_and_Skin_Clinic_Logo.html\" target=\"_blank\" rel=\"nofollow\"><img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/2170144\/Dr_U_Hair_and_Skin_Clinic_Logo.jpg\" title=\"Dr. U Hair and Skin Clinic (PRNewsfoto\/Dr. U Hair and Skin Clinic)\" alt=\"Dr. U Hair and Skin Clinic (PRNewsfoto\/Dr. U Hair and Skin Clinic)\" \/><\/a><\/p>\n<\/div>\n<p>V\u00eddeo &#8211; <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=pt&amp;o=4604135-1&amp;h=10502231&amp;u=https%3A%2F%2Fwww.youtube.com%2Fwatch%3Fv%3DS3MXQSqFAgI&amp;a=https%3A%2F%2Fwww.youtube.com%2Fwatch%3Fv%3DS3MXQSqFAgI\" target=\"_blank\" rel=\"nofollow\">https:\/\/www.youtube.com\/watch?v=S3MXQSqFAgI<\/a><br \/>Foto &#8211; <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=pt&amp;o=4604135-1&amp;h=2499425632&amp;u=https%3A%2F%2Fmma.prnewswire.com%2Fmedia%2F2870362%2F5739883%2FDr__U_Hair_and_Skin_Clinic__piilif_aga_norwood_7_strip_scar_hair_transplant_before_after.jpg&amp;a=https%3A%2F%2Fmma.prnewswire.com%2Fmedia%2F2870362%2F5739883%2FDr__U_Hair_and_Skin_Clinic__piilif_aga_norwood_7_strip_scar_hair_transplant_before_after.jpg\" target=\"_blank\" rel=\"nofollow\">https:\/\/mma.prnewswire.com\/media\/2870362\/5739883\/Dr__U_Hair_and_Skin_Clinic__piilif_aga_norwood_7_strip_scar_hair_transplant_before_after.jpg<\/a><br \/>Logotipo &#8211; <a href=\"https:\/\/edge.prnewswire.com\/c\/link\/?t=0&amp;l=pt&amp;o=4604135-1&amp;h=4102906267&amp;u=https%3A%2F%2Fmma.prnewswire.com%2Fmedia%2F2170144%2F5739884%2FDr_U_Hair_and_Skin_Clinic_Logo.jpg&amp;a=https%3A%2F%2Fmma.prnewswire.com%2Fmedia%2F2170144%2F5739884%2FDr_U_Hair_and_Skin_Clinic_Logo.jpg\" target=\"_blank\" rel=\"nofollow\">https:\/\/mma.prnewswire.com\/media\/2170144\/5739884\/Dr_U_Hair_and_Skin_Clinic_Logo.jpg<\/a><\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder0\"><\/div>\n<p id=\"PURL\"><img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=PT71795&amp;sd=2026-01-27\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/novo-estudo-identifica-inflamacao-oculta-no-couro-cabeludo-que-pode-explicar-por-que-os-tratamentos-para-a-calvicie-androgenetica-param-de-funcionar-302672584.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/novo-estudo-identifica-inflamacao-oculta-no-couro-cabeludo-que-pode-explicar-por-que-os-tratamentos-para-a-calvicie-androgenetica-param-de-funcionar-302672584.html<\/a><\/p>\n<p>FONTE Dr. U Hair and Skin Clinic<\/p>\n<\/div>\n<p>  <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=PT71795&amp;Transmission_Id=202601270900PR_NEWS_LATAM____PT71795&amp;DateId=20260128\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n<p><strong>T\u00f3picos Relacionados:<\/strong> Pesquisa, Enquetes e Estudos, M\u00e9dico \/ Farmac\u00eautico, Sa\u00fade\/Hospitais, An\u00fancios de Transmiss\u00e3o, Dom\u00e9stico\/Consumidor\/Cosm\u00e9ticos<\/p>\n<p>A <b>OESP<\/b> n\u00e3o \u00e9(s\u00e3o) respons\u00e1vel(is) por erros, incorre\u00e7\u00f5es, atrasos ou quaisquer decis\u00f5es tomadas por seus clientes com base nos Conte\u00fados ora disponibilizados, bem como tais Conte\u00fados n\u00e3o representam a opini\u00e3o da <b>OESP<\/b> e s\u00e3o de inteira responsabilidade da <b>PR Newswire Ltda<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"Artigo de acesso aberto descreve PIILIF, um padr\u00e3o inflamat\u00f3rio e fibr\u00f3tico precoce centrado nos fol\u00edculos, encontrado mesmo em couros cabeludos com apar\u00eancia normal. MANHATTAN BEACH,","protected":false},"author":1,"featured_media":123345,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[6571,6569,6568,6570],"class_list":["post-123344","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prnewswire","tag-calvicie-masculina","tag-na-regiao-de-los-angeles","tag-pesquisadores-da-clinica-dr-u-hair-and-skin","tag-relatam-que-um-padrao-inflamatorio-e-fibrotico-precoce-na-alopecia-androgenetica-aga"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/123344","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/comments?post=123344"}],"version-history":[{"count":0,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/123344\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media\/123345"}],"wp:attachment":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media?parent=123344"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/categories?post=123344"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/tags?post=123344"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}