{"id":117322,"date":"2025-10-10T12:42:00","date_gmt":"2025-10-10T15:42:00","guid":{"rendered":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/centro-nacional-de-inovacao-tecnologica-para-laticinios-realiza-sua-terceira-conferencia-anual-na-mongolia-interior-china\/"},"modified":"2025-10-10T12:42:00","modified_gmt":"2025-10-10T15:42:00","slug":"centro-nacional-de-inovacao-tecnologica-para-laticinios-realiza-sua-terceira-conferencia-anual-na-mongolia-interior-china","status":"publish","type":"post","link":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/prnewswire\/centro-nacional-de-inovacao-tecnologica-para-laticinios-realiza-sua-terceira-conferencia-anual-na-mongolia-interior-china\/","title":{"rendered":"Centro Nacional de Inova\u00e7\u00e3o Tecnol\u00f3gica para Latic\u00ednios realiza sua terceira confer\u00eancia anual na Mong\u00f3lia Interior, China"},"content":{"rendered":"\n<div class=\"xn-content\">\n<p><span class=\"legendSpanClass\">HOHHOT, China<\/span>, <span class=\"legendSpanClass\">10 de outubro de 2025<\/span> \/PRNewswire\/ &#8212; O Centro Nacional de Inova\u00e7\u00e3o Tecnol\u00f3gica em Latic\u00ednios (NCTID) realizou sua terceira confer\u00eancia anual nos dias 27 e 28 de setembro em Hohhot, Mong\u00f3lia Interior.<\/p>\n<p>Na confer\u00eancia, o NCTID revelou suas Dez Principais Conquistas para 2025, destacando avan\u00e7os importantes que estabelecem novos padr\u00f5es para o setor. Essas conquistas incluem a cria\u00e7\u00e3o de gado leiteiro de classe mundial, o avan\u00e7o da pesquisa sobre leite materno, a amplia\u00e7\u00e3o da produ\u00e7\u00e3o de ingredientes essenciais, o refinamento de tecnologias avan\u00e7adas de processamento de latic\u00ednios, o desenvolvimento de produtos l\u00e1cteos para um envelhecimento saud\u00e1vel e a promo\u00e7\u00e3o da sustentabilidade em todo o setor.<\/p>\n<p>He Jian, gerente geral do NCTID, analisou o progresso e as perspectivas do Centro. &#8220;Os \u00faltimos tr\u00eas anos foram um per\u00edodo de forma\u00e7\u00e3o de explora\u00e7\u00e3o para o NCTID, durante o qual estabelecemos uma plataforma aberta e colaborativa do setor&#8221;, observou ele. &#8220;Olhando para o futuro, vamos aprimorar nosso foco na pesquisa com incuba\u00e7\u00e3o de neg\u00f3cios no centro, ao mesmo tempo em que elevamos a confer\u00eancia anual a um f\u00f3rum cient\u00edfico profissional de alto n\u00edvel.&#8221;<\/p>\n<p>Especialistas de institui\u00e7\u00f5es l\u00edderes, incluindo a Universidade Agr\u00edcola da China, a Universidade de Tecnologia e Neg\u00f3cios de Pequim, a Universidade da Mong\u00f3lia Interior e o Instituto de Ci\u00eancias da Bioeconomia da Nova Zel\u00e2ndia, tamb\u00e9m compartilharam suas pesquisas na confer\u00eancia.<\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder7605\">\n  <a href=\"https:\/\/mma.prnewswire.com\/media\/2792406\/Experts_shared_research_conference.html\" target=\"_blank\" rel=\"nofollow\"> <img decoding=\"async\" src=\"https:\/\/mma.prnewswire.com\/media\/2792406\/Experts_shared_research_conference.jpg\" title=\"Especialistas compartilharam suas pesquisas na confer\u00eancia (PRNewsfoto\/Yili Group)\" alt=\"Especialistas compartilharam suas pesquisas na confer\u00eancia (PRNewsfoto\/Yili Group)\" \/>  <\/a>\n<\/p>\n<\/p><\/div>\n<p>O Dr. Stefan Clerens, gerente do Grupo Cient\u00edfico de Alimentos Inteligentes e Bioprodutos do Instituto de Ci\u00eancias da Bioeconomia, discutiu o progresso recente do instituto na ci\u00eancia de alimentos. Sua palestra destacou um pipeline de desenvolvimento para alimentos saud\u00e1veis para o c\u00e9rebro, enfatizando que o uso de modelos de c\u00e9lulas do eixo intestino-c\u00e9rebro para triagem pode reduzir os riscos de P&amp;D e fornecer forte suporte para a inova\u00e7\u00e3o de produtos.<\/p>\n<p>O perfil internacional do NCTID continua a crescer, como evidenciado pelo lan\u00e7amento do <i>Ponto Focal de Pesquisa em Latic\u00ednios na China<\/i>, uma publica\u00e7\u00e3o especial da <i>Nature<\/i> que mostrou as conquistas colaborativas do NCTID e de suas organiza\u00e7\u00f5es membros, incluindo a Yili. A publica\u00e7\u00e3o destaca o papel fundamental do Centro na conex\u00e3o entre pesquisa e aplica\u00e7\u00e3o industrial, fomentando a inova\u00e7\u00e3o e o desenvolvimento no setor de latic\u00ednios.<\/p>\n<p>Al\u00e9m disso, o NCTID e o Centro de Prote\u00e7\u00e3o \u00e0 Propriedade Intelectual da Mong\u00f3lia Interior divulgaram os resultados de seu estudo conjunto de 2025, <i>Uma Pesquisa do Ambiente Legal de Propriedade Intelectual no Sudeste Asi\u00e1tico e Recomenda\u00e7\u00f5es Estrat\u00e9gicas para a Expans\u00e3o Internacional de Empresas de Latic\u00ednios<\/i>.<\/p>\n<p>Liderada pelo Yili Group, o NCTID se tornou uma for\u00e7a motriz no avan\u00e7o e aplica\u00e7\u00e3o de altas tecnologias, promovendo o progresso de todo o setor e apoiando o desenvolvimento de alta qualidade do setor de latic\u00ednios da China.<\/p>\n<p>Olhando para o futuro, o NCTID planeja adotar uma abordagem mais aberta \u00e0 colabora\u00e7\u00e3o, envolvendo governos, empresas, universidades, institutos de pesquisa e partes interessadas em toda a cadeia de suprimentos. Ao oferecer inova\u00e7\u00f5es mais frequentes e servi\u00e7os p\u00fablicos mais inclusivos, o Centro visa fornecer um apoio mais s\u00f3lido ao crescimento a longo prazo do setor de latic\u00ednios da China.<\/p>\n<p>Foto &#8211; <a href=\"https:\/\/mma.prnewswire.com\/media\/2792406\/Experts_shared_research_conference.jpg\" target=\"_blank\" rel=\"nofollow\">https:\/\/mma.prnewswire.com\/media\/2792406\/Experts_shared_research_conference.jpg<\/a><\/p>\n<div class=\"PRN_ImbeddedAssetReference\" id=\"DivAssetPlaceHolder0\"><\/div>\n<p id=\"PURL\">\n<img loading=\"lazy\" decoding=\"async\" title=\"Cision\" width=\"12\" height=\"12\" alt=\"Cision\" src=\"https:\/\/edge.prnewswire.com\/c\/img\/favicon.png?sn=PT94132&amp;sd=2025-10-10\" \/> View original content to download multimedia:<a id=\"PRNURL\" rel=\"nofollow\" href=\"https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/centro-nacional-de-inovacao-tecnologica-para-laticinios-realiza-sua-terceira-conferencia-anual-na-mongolia-interior-china-302580974.html\" target=\"_blank\">https:\/\/www.prnewswire.com\/br\/comunicados-para-a-imprensa\/centro-nacional-de-inovacao-tecnologica-para-laticinios-realiza-sua-terceira-conferencia-anual-na-mongolia-interior-china-302580974.html<\/a><\/p>\n<p>FONTE Yili Group<\/p>\n<\/p><\/div>\n<p>  <img decoding=\"async\" alt=\"\" src=\"https:\/\/rt.prnewswire.com\/rt.gif?NewsItemId=PT94132&amp;Transmission_Id=202510101131PR_NEWS_LATAM____PT94132&amp;DateId=20251010\" style=\"border:0px;width:1px;height:1px\" \/><\/p>\n<p><strong>T\u00f3picos Relacionados:<\/strong> Bebidas, Alimentos, Not\u00edcias de Feiras Comerciais, Varejo, Bebidas N\u00e3o Alco\u00f3licas<\/p>\n<p>A <b>OESP<\/b> n\u00e3o \u00e9(s\u00e3o) respons\u00e1vel(is) por erros, incorre\u00e7\u00f5es, atrasos ou quaisquer decis\u00f5es tomadas por seus clientes com base nos Conte\u00fados ora disponibilizados, bem como tais Conte\u00fados n\u00e3o representam a opini\u00e3o da <b>OESP<\/b> e s\u00e3o de inteira responsabilidade da <b>PR Newswire Ltda<\/b><\/p>\n","protected":false},"excerpt":{"rendered":"HOHHOT, China, 10 de outubro de 2025 \/PRNewswire\/ &#8212; O Centro Nacional de Inova\u00e7\u00e3o Tecnol\u00f3gica em Latic\u00ednios (NCTID) realizou sua terceira confer\u00eancia anual nos dias 27 e 28 de setembro em","protected":false},"author":1,"featured_media":117323,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":""},"categories":[27],"tags":[3159,3158],"class_list":["post-117322","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-prnewswire","tag-mongolia-interior","tag-o-centro-nacional-de-inovacao-tecnologica-em-laticinios-nctid-realizou-sua-terceira-conferencia-anual-nos-dias-27-e-28-de-setembro-em-hohhot"],"acf":[],"_links":{"self":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/117322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/comments?post=117322"}],"version-history":[{"count":0,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/posts\/117322\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media\/117323"}],"wp:attachment":[{"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/media?parent=117322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/categories?post=117322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/bluestudio.estadao.com.br\/agencia-de-comunicacao\/wp-json\/wp\/v2\/tags?post=117322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}